{"id":1,"count":5,"description":"","link":"https:\/\/robdanger.com\/website_9241ff7a\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncategorized Archives - Chocolate Journey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/category\/uncategorized\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized Archives - Chocolate Journey\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/category\/uncategorized\/\" \/>\n<meta property=\"og:site_name\" content=\"Chocolate Journey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/teq.nbd.temporary.site\\\/website_9241ff7a\\\/category\\\/uncategorized\\\/\",\"url\":\"https:\\\/\\\/teq.nbd.temporary.site\\\/website_9241ff7a\\\/category\\\/uncategorized\\\/\",\"name\":\"Uncategorized Archives - Chocolate Journey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teq.nbd.temporary.site\\\/website_9241ff7a\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teq.nbd.temporary.site\\\/website_9241ff7a\\\/category\\\/uncategorized\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teq.nbd.temporary.site\\\/website_9241ff7a\\\/category\\\/uncategorized\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/teq.nbd.temporary.site\\\/website_9241ff7a\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teq.nbd.temporary.site\\\/website_9241ff7a\\\/#website\",\"url\":\"https:\\\/\\\/teq.nbd.temporary.site\\\/website_9241ff7a\\\/\",\"name\":\"Chocolate Journey\",\"description\":\"Exploring chocolate makers, origins, flavors, stories, and unforgettable tastings from around the world.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teq.nbd.temporary.site\\\/website_9241ff7a\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncategorized Archives - Chocolate Journey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/category\/uncategorized\/","og_locale":"en_US","og_type":"article","og_title":"Uncategorized Archives - Chocolate Journey","og_url":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/category\/uncategorized\/","og_site_name":"Chocolate Journey","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/category\/uncategorized\/","url":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/category\/uncategorized\/","name":"Uncategorized Archives - Chocolate Journey","isPartOf":{"@id":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/#website"},"breadcrumb":{"@id":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/category\/uncategorized\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/category\/uncategorized\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/#website","url":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/","name":"Chocolate Journey","description":"Exploring chocolate makers, origins, flavors, stories, and unforgettable tastings from around the world.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teq.nbd.temporary.site\/website_9241ff7a\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/robdanger.com\/website_9241ff7a\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robdanger.com\/website_9241ff7a\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/robdanger.com\/website_9241ff7a\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/robdanger.com\/website_9241ff7a\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}